{"id":7761,"date":"2015-10-22T17:44:54","date_gmt":"2015-10-22T15:44:54","guid":{"rendered":"http:\/\/www.techsealab.com\/en\/?p=7761"},"modified":"2015-10-27T17:25:58","modified_gmt":"2015-10-27T16:25:58","slug":"sauce-au-vinaigre-de-cidre-facon-beurre-blanc","status":"publish","type":"post","link":"https:\/\/www.techsealab.com\/en\/sauce-au-vinaigre-de-cidre-facon-beurre-blanc","title":{"rendered":"Sauce au vinaigre de cidre fa\u00e7on beurre blanc"},"content":{"rendered":"<h2>Recette compos\u00e9e par le <a href=\"https:\/\/www.facebook.com\/LaVoilerieRestaurant\" target=\"_blank\">Restaurant LA VOILERIE<\/a><br \/>600 Rue du Phare &#8211; 29760, Penmarc\u2019h<\/h2>\n<h3>Sauce au vinaigre de cidre fa\u00e7on beurre blanc<\/h3>\n<h4>Pour 6 personnes :<\/h4>\n<ul>\n<li style=\"list-style: none;\">1 \u00e9chalote<\/li>\n<li style=\"list-style: none;\">100 ml de vinaigre de cidre marin<\/li>\n<li style=\"list-style: none;\">100 gr de beurre doux<\/li>\n<li style=\"list-style: none;\">100 ml de cr\u00e8me liquide<\/li>\n<li style=\"list-style: none;\">1 cuiller \u00e0 soupe de farine<\/li>\n<li style=\"list-style: none;\">1 cuiller \u00e0 caf\u00e9 de sucre en poudre<\/li>\n<\/ul>\n<h4>Pr\u00e9paration :<\/h4>\n<p style=\"text-align: justify;\">Ciseler l\u2019\u00e9chalote et la faire revenir \u00e0 feux doux dans une casserole avec le beurre.<\/p>\n<p style=\"text-align: justify;\">Ajouter la farine et m\u00e9langer \u00e0 la cuiller pour obtenir une p\u00e2te (un roux).<\/p>\n<p style=\"text-align: justify;\">Verser le vinaigre de cidre, le sucre puis la cr\u00e8me. Laisser cuire quelques minutes.<\/p>\n<p style=\"text-align: justify;\">Ajouter du poivre, go\u00fbter et servir.<\/p>\n<p style=\"text-align: justify;\"><strong>Cette sauce est id\u00e9ale pour accompagner tous vos poissons.<\/strong><\/p>\n\r\n<script language=\"javascript\"> \r\njQuery(document).ready(function() {\r\n\tjQuery(\"#testimonials\").carousel({\r\n\t\tslider : \".t-slider\",\r\n\t\tslide : \".t-slide\",\r\n\t\tslideHed : \".slidehed\",\r\n\t\tnextSlide : \".next\",\r\n\t\tprevSlide : \".prev\",\r\n\t\taddPagination : false,\r\n\t\taddNav : false,\r\n\t\tbackToStart: false\r\n\t});\r\n});\r\n<\/script>\r\n<style type=\"text\/css\">\r\n#testimonials {\r\n\tdisplay: inline;\r\n\tfloat: left;\r\n\tposition: relative;\r\n\tmargin-right: 0;\r\n}\r\n#testimonials ul {\r\n\tmargin: 0;\r\n\tpadding: 0;\r\n\tlist-style: none;\r\n}\r\n#testimonials .t-slide {\r\n\tcolor: #606060;\r\n}\r\n#testimonials h3.testimonial-header-title {\r\n\tdisplay:none;\r\n\tfont-size: 19px;\r\n\tfont-weight:bold;\r\n\tmargin: 5px 0px 11px 0;\r\n\tmin-height: 25px;\r\n}\r\n.testimonials-author {\r\n    display: block;\r\n    float: right;\r\n    margin-bottom: 20px;\r\n    margin-top: -23px;\r\n}\r\n.testimonials-bg {\r\n    background: url(https:\/\/www.techsealab.com\/wp-content\/plugins\/rotating-testimonials\/testimonials-bg.png) no-repeat scroll 0 0 transparent;\r\n    display: block;\r\n    height: 30px;\r\n    margin-left: 25px;\r\n    margin-top: -1px;\r\n    width: 200px;\r\n}\r\n\r\n#testimonials .slidecontrols {\r\n\tdisplay: none;\r\n    float: right;\r\n    height: 40px;\r\n    margin: 0 0 5px;\r\n    position: relative;\r\n}\r\n#testimonials .slidecontrols li {\r\n\tdisplay: inline;\r\n}\r\n#testimonials .slidecontrols li.right, #testimonials .slidecontrols li.left { \r\n\tfloat: right;\r\n    margin-top: 7px;\r\n}\r\n#testimonials .slidecontrols .prev {\r\n\t background-position: -10px -4px;\r\n}\r\n#testimonials .slidecontrols .next {\r\n\tbackground-position: -49px -4px;\r\n}\r\n#testimonials .slidecontrols .prev:hover {\r\n\t  background-position: -10px -41px;\r\n}\r\n#testimonials .slidecontrols .next:hover {\r\n\tbackground-position: -49px -41px;\r\n}\r\n#testimonials .slidecontrols .prev,.slidecontrols .next {\r\n\tbackground-image: url(https:\/\/www.techsealab.com\/wp-content\/plugins\/rotating-testimonials\/navigation.png);\r\n\tbackground-position: initial initial;\r\n\tbackground-repeat: initial initial;\r\n\t display: block;\r\n    font-size: 0;\r\n    height: 26px;\r\n    line-height: 0;\r\n    width: 22px;\r\n}\r\n\r\n#testimonials .testimonial-quote {\r\n\tbackground: #F6F6F6;\r\n    border-radius: 2px;\r\n    box-shadow: 0 -1px 0 0 rgba(0, 0, 0, 0.06) inset;\r\n    line-height: 21px;\r\n    padding: 20px;\r\n\tmargin:0px;\r\n\tcolor: #888888;\r\n    line-height: 21px;\r\n    padding: 25px;\r\n}\r\n<\/style><div id=\"testimonials\" data-autorotate=\"5000\"><ul class=\"slidecontrols\"><li class=\"right\"><a href=\"#sliderName\" class=\"next\"><\/a><\/li><li class=\"left\"><a href=\"#sliderName\" class=\"prev\"><\/a><\/li><\/ul><h3 class=\"testimonial-header-title\">Lo\u00efc Sannier<\/h3><ul class=\"t-slider\" id=\"sliderName\"><li class=\"t-slide\"><p class=\"testimonial-quote\">Je suis heureux de partager avec vous cette recette qui fera le plaisir de vos papilles et comblera de satisfaction vos invit\u00e9s.<\/p><div class=\"testimonials-bg\"><\/div><div class=\"testimonials-author\">Jean-Claude Spegagne,&nbsp;Chef Cuisinier,&nbsp;\r\n        \t\t<a href=\"http:\/\/www.restaurant-hotels.com\" title=\"H\u00f4tel Restaurant Traiteur Le Bienvenue \u00e0 Roudouallec\">H\u00f4tel Restaurant Traiteur Le Bienvenue \u00e0 Roudouallec<\/a><\/div><\/li><li class=\"t-slide\"><p class=\"testimonial-quote\">Je vous propose cette recette, qui je l'esp\u00e8re, ravira vos papilles.<\/p><div class=\"testimonials-bg\"><\/div><div class=\"testimonials-author\">Lo\u00efc Sannier,&nbsp;Chef Cuisinier,&nbsp;\r\n        \t\t<a href=\"http:\/\/www.hotelstgue.com\" title=\"H\u00f4tel Restaurant de la Mer \u00e0 Saint Gu\u00e9nol\u00e9\">H\u00f4tel Restaurant de la Mer \u00e0 Saint Gu\u00e9nol\u00e9<\/a><\/div><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Recette compos\u00e9e par le Restaurant LA VOILERIE600 Rue du Phare &#8211; 29760, Penmarc\u2019h Sauce au vinaigre de cidre fa\u00e7on beurre blanc Pour 6 personnes : 1 \u00e9chalote 100 ml de vinaigre de cidre marin 100 gr de beurre doux 100 ml de cr\u00e8me liquide 1 cuiller \u00e0 soupe de farine 1 cuiller \u00e0 caf\u00e9 de sucre en poudre Pr\u00e9paration :.<\/p>\n","protected":false},"author":3,"featured_media":7759,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"image","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[39],"tags":[],"class_list":["post-7761","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-food","post_format-post-format-image"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.techsealab.com\/wp-content\/uploads\/2015\/10\/sauce-au-vinaigre-de-cidre-fa%C3%A7on-beurre-blanc.jpg?fit=605%2C300&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.techsealab.com\/en\/wp-json\/wp\/v2\/posts\/7761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.techsealab.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.techsealab.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.techsealab.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.techsealab.com\/en\/wp-json\/wp\/v2\/comments?post=7761"}],"version-history":[{"count":0,"href":"https:\/\/www.techsealab.com\/en\/wp-json\/wp\/v2\/posts\/7761\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.techsealab.com\/en\/wp-json\/wp\/v2\/media\/7759"}],"wp:attachment":[{"href":"https:\/\/www.techsealab.com\/en\/wp-json\/wp\/v2\/media?parent=7761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.techsealab.com\/en\/wp-json\/wp\/v2\/categories?post=7761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.techsealab.com\/en\/wp-json\/wp\/v2\/tags?post=7761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}